{"id":5958,"count":3,"description":"<strong>Special 2 euro currency<\/strong><strong>n collecting Vatican City?<\/strong>\r\n\r\nEen populair verzamelobject sinds 2004 toen de 1e speciale 2 euromunt werd geslagen. Deze 2 euro\u2019s kregen een speciale afbeelding die niet op de reguliere 2 euromunt staat. De munten worden geslagen met een bijzonder thema op de achterzijde van de munt.\r\n\r\nBekijk nu ons ruime aanbod speciale 2 euro gelegenheidsmunten vanaf 2004 t\/m heden. Ons aanbod munten is in nieuwe \/ ongecirculeerde kwaliteit (tenzij anders vermeld). Gratis verzending vanaf 75 euro binnen Nederland.","link":"https:\/\/www.david-coin.com\/en\/product-category\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/","name":"Special 2 euro coins Vatican City","slug":"speciale-2-euromunten-vaticaanstad","taxonomy":"product_cat","parent":5934,"meta":[],"menu_order":155,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>speciale-2-euromunten-vaticaanstad<\/title>\n<meta name=\"description\" content=\"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\/m heden. Gratis verzending vanaf 75 euro binnen NL.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.david-coin.com\/en\/product-category\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Speciale 2 euromunten Vaticaanstad Archieven\" \/>\n<meta property=\"og:description\" content=\"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\/m heden. Gratis verzending vanaf 75 euro binnen NL.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.david-coin.com\/en\/product-category\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/\" \/>\n<meta property=\"og:site_name\" content=\"David Coin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/speciale-2-euromunten-per-land\\\/speciale-2-euromunten-vaticaanstad\\\/\",\"url\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/speciale-2-euromunten-per-land\\\/speciale-2-euromunten-vaticaanstad\\\/\",\"name\":\"speciale-2-euromunten-vaticaanstad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#website\"},\"description\":\"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\\\/m heden. Gratis verzending vanaf 75 euro binnen NL.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/speciale-2-euromunten-per-land\\\/speciale-2-euromunten-vaticaanstad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/speciale-2-euromunten-per-land\\\/speciale-2-euromunten-vaticaanstad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.david-coin.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euromunten\",\"item\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Speciale 2 euromunten\",\"item\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Speciale 2 euromunten per land\",\"item\":\"https:\\\/\\\/www.david-coin.com\\\/product-categorie\\\/zeldzame-euromunten\\\/speciale-2-euromunten\\\/speciale-2-euromunten-per-land\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Speciale 2 euromunten Vaticaanstad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#website\",\"url\":\"https:\\\/\\\/www.david-coin.com\\\/\",\"name\":\"David Coin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.david-coin.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#organization\",\"name\":\"David Coin\",\"url\":\"https:\\\/\\\/www.david-coin.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.david-coin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/davidcoin-logo-final.png\",\"contentUrl\":\"https:\\\/\\\/www.david-coin.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/davidcoin-logo-final.png\",\"width\":800,\"height\":267,\"caption\":\"David Coin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.david-coin.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Davidcoininkoopenverkoop\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC39lihLKFSPTff0w6tv0pWQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"speciale-2-euromunten-vaticaanstad","description":"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\/m heden. Gratis verzending vanaf 75 euro binnen NL.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.david-coin.com\/en\/product-category\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/","og_locale":"en_US","og_type":"article","og_title":"Speciale 2 euromunten Vaticaanstad Archieven","og_description":"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\/m heden. Gratis verzending vanaf 75 euro binnen NL.","og_url":"https:\/\/www.david-coin.com\/en\/product-category\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/","og_site_name":"David Coin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/","url":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/","name":"speciale-2-euromunten-vaticaanstad","isPartOf":{"@id":"https:\/\/www.david-coin.com\/#website"},"description":"Speciale 2 euromunten Vaticaanstad verzamelen? Bekijk nu ons aanbod speciale 2 euromunten vanaf 2004 t\/m heden. Gratis verzending vanaf 75 euro binnen NL.","breadcrumb":{"@id":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/speciale-2-euromunten-vaticaanstad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.david-coin.com\/"},{"@type":"ListItem","position":2,"name":"Euromunten","item":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/"},{"@type":"ListItem","position":3,"name":"Speciale 2 euromunten","item":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/"},{"@type":"ListItem","position":4,"name":"Speciale 2 euromunten per land","item":"https:\/\/www.david-coin.com\/product-categorie\/zeldzame-euromunten\/speciale-2-euromunten\/speciale-2-euromunten-per-land\/"},{"@type":"ListItem","position":5,"name":"Speciale 2 euromunten Vaticaanstad"}]},{"@type":"WebSite","@id":"https:\/\/www.david-coin.com\/#website","url":"https:\/\/www.david-coin.com\/","name":"David Coin","description":"","publisher":{"@id":"https:\/\/www.david-coin.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.david-coin.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.david-coin.com\/#organization","name":"David Coin","url":"https:\/\/www.david-coin.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.david-coin.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.david-coin.com\/wp-content\/uploads\/2024\/04\/davidcoin-logo-final.png","contentUrl":"https:\/\/www.david-coin.com\/wp-content\/uploads\/2024\/04\/davidcoin-logo-final.png","width":800,"height":267,"caption":"David Coin"},"image":{"@id":"https:\/\/www.david-coin.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Davidcoininkoopenverkoop","https:\/\/www.youtube.com\/channel\/UC39lihLKFSPTff0w6tv0pWQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.david-coin.com\/en\/wp-json\/wp\/v2\/product_cat\/5958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.david-coin.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.david-coin.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.david-coin.com\/en\/wp-json\/wp\/v2\/product_cat\/5934"}],"wp:post_type":[{"href":"https:\/\/www.david-coin.com\/en\/wp-json\/wp\/v2\/product?product_cat=5958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}